{"id":34826,"date":"2023-03-10T17:54:00","date_gmt":"2023-03-10T17:54:00","guid":{"rendered":"https:\/\/fermentierra.com\/?page_id=34826"},"modified":"2023-03-10T17:54:03","modified_gmt":"2023-03-10T17:54:03","slug":"remboursements_retours","status":"publish","type":"page","link":"https:\/\/fermentierra.com\/en\/remboursements_retours\/","title":{"rendered":"Refunds and returns policy"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Overview<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Our refund policy is 30 days. If 30 days have passed since your purchase, we cannot offer you a full refund.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">We do not accept returns on our products.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Reimbursement<\/strong>t<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">You are entitled to a refund if the goods have been damaged on delivery or if, on opening them, you discover that the product has deteriorated before the date (xx\/yy).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Once you have contacted us and the refund is requested, you will be asked to provide your bank details so that we can proceed with the transfer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Need help?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contact us at fermentierra.commande@gmail.com for any questions regarding refunds and returns.<\/p>","protected":false},"excerpt":{"rendered":"<p>Vue d&rsquo;ensemble Notre politique de remboursement est de 30 jours. Si 30 jours se sont \u00e9coul\u00e9s depuis votre achat, nous ne pouvons pas vous offrir un remboursement complet. Nous n&rsquo;acceptons pas les retours de nos produits. Remboursement Vous pouvez pr\u00e9tendre \u00e0 un remboursement si la&nbsp;<a class=\"read-more\" href=\"https:\/\/fermentierra.com\/en\/remboursements_retours\/\">...<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-34826","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Vue d&#039;ensemble Notre politique de remboursement est de 30 jours. Si 30 jours se sont \u00e9coul\u00e9s depuis votre achat, nous ne pouvons pas vous offrir un remboursement complet. Nous n&#039;acceptons pas les retours de nos produits. Remboursement Vous pouvez pr\u00e9tendre \u00e0 un remboursement si la marchandise a \u00e9t\u00e9 endommag\u00e9e lors de la livraison ou si,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"vzlGkp0avkDiegdCyCkDigjpo9shigDAmdpk3nXtou4\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/fermentierra.com\/en\/remboursements_retours\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Fermentierra - saveurs lactoferment\u00e9es\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Politique en mati\u00e8re de remboursements et de retours - Fermentierra\" \/>\n\t\t<meta property=\"og:description\" content=\"Vue d&#039;ensemble Notre politique de remboursement est de 30 jours. Si 30 jours se sont \u00e9coul\u00e9s depuis votre achat, nous ne pouvons pas vous offrir un remboursement complet. Nous n&#039;acceptons pas les retours de nos produits. Remboursement Vous pouvez pr\u00e9tendre \u00e0 un remboursement si la marchandise a \u00e9t\u00e9 endommag\u00e9e lors de la livraison ou si,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/fermentierra.com\/en\/remboursements_retours\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/qb233zbtdie.preview.infomaniak.website\/wp-content\/uploads\/2025\/04\/cropped-logo-entreprise-fermentierra-detoure.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/qb233zbtdie.preview.infomaniak.website\/wp-content\/uploads\/2025\/04\/cropped-logo-entreprise-fermentierra-detoure.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-03-10T17:54:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-03-10T17:54:03+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fermentierra\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Politique en mati\u00e8re de remboursements et de retours - Fermentierra\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Vue d&#039;ensemble Notre politique de remboursement est de 30 jours. Si 30 jours se sont \u00e9coul\u00e9s depuis votre achat, nous ne pouvons pas vous offrir un remboursement complet. Nous n&#039;acceptons pas les retours de nos produits. Remboursement Vous pouvez pr\u00e9tendre \u00e0 un remboursement si la marchandise a \u00e9t\u00e9 endommag\u00e9e lors de la livraison ou si,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/qb233zbtdie.preview.infomaniak.website\/wp-content\/uploads\/2025\/04\/cropped-logo-entreprise-fermentierra-detoure.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/remboursements_retours\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fermentierra.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/remboursements_retours\\\/#listItem\",\"name\":\"Politique en mati\\u00e8re de remboursements et de retours\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/remboursements_retours\\\/#listItem\",\"position\":2,\"name\":\"Politique en mati\\u00e8re de remboursements et de retours\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/#organization\",\"name\":\"Fermentierra\",\"description\":\"Fermentierra saveurs lactoferment\\u00e9es\",\"url\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/qb233zbtdie.preview.infomaniak.website\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/cropped-logo-entreprise-fermentierra-detoure.png\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/remboursements_retours\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/remboursements_retours\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fermentierra\\\/\",\"https:\\\/\\\/www.instagram.com\\\/fermentierra\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/remboursements_retours\\\/#webpage\",\"url\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/remboursements_retours\\\/\",\"name\":\"Politique en mati\\u00e8re de remboursements et de retours - Fermentierra\",\"description\":\"Vue d'ensemble Notre politique de remboursement est de 30 jours. Si 30 jours se sont \\u00e9coul\\u00e9s depuis votre achat, nous ne pouvons pas vous offrir un remboursement complet. Nous n'acceptons pas les retours de nos produits. Remboursement Vous pouvez pr\\u00e9tendre \\u00e0 un remboursement si la marchandise a \\u00e9t\\u00e9 endommag\\u00e9e lors de la livraison ou si,\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/remboursements_retours\\\/#breadcrumblist\"},\"datePublished\":\"2023-03-10T17:54:00+00:00\",\"dateModified\":\"2023-03-10T17:54:03+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/\",\"name\":\"fermentierra\",\"description\":\"saveurs lactoferment\\u00e9es\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Refunds and returns policy - Fermentierra","description":"Overview Our refund policy is 30 days. If 30 days have passed since your purchase, we cannot offer you a full refund. We do not accept returns on our products. Refund You are entitled to a refund if the goods were damaged during delivery or if,","canonical_url":"https:\/\/fermentierra.com\/en\/remboursements_retours\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"vzlGkp0avkDiegdCyCkDigjpo9shigDAmdpk3nXtou4","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/fermentierra.com\/en\/remboursements_retours\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/fermentierra.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/fermentierra.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/fermentierra.com\/en\/remboursements_retours\/#listItem","name":"Politique en mati\u00e8re de remboursements et de retours"}},{"@type":"ListItem","@id":"https:\/\/fermentierra.com\/en\/remboursements_retours\/#listItem","position":2,"name":"Politique en mati\u00e8re de remboursements et de retours","previousItem":{"@type":"ListItem","@id":"https:\/\/fermentierra.com\/en#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/fermentierra.com\/en\/#organization","name":"Fermentierra","description":"Fermentierra saveurs lactoferment\u00e9es","url":"https:\/\/fermentierra.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/qb233zbtdie.preview.infomaniak.website\/wp-content\/uploads\/2025\/04\/cropped-logo-entreprise-fermentierra-detoure.png","@id":"https:\/\/fermentierra.com\/en\/remboursements_retours\/#organizationLogo"},"image":{"@id":"https:\/\/fermentierra.com\/en\/remboursements_retours\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/fermentierra\/","https:\/\/www.instagram.com\/fermentierra\/"]},{"@type":"WebPage","@id":"https:\/\/fermentierra.com\/en\/remboursements_retours\/#webpage","url":"https:\/\/fermentierra.com\/en\/remboursements_retours\/","name":"Politique en mati\u00e8re de remboursements et de retours - Fermentierra","description":"Vue d'ensemble Notre politique de remboursement est de 30 jours. Si 30 jours se sont \u00e9coul\u00e9s depuis votre achat, nous ne pouvons pas vous offrir un remboursement complet. Nous n'acceptons pas les retours de nos produits. Remboursement Vous pouvez pr\u00e9tendre \u00e0 un remboursement si la marchandise a \u00e9t\u00e9 endommag\u00e9e lors de la livraison ou si,","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/fermentierra.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/fermentierra.com\/en\/remboursements_retours\/#breadcrumblist"},"datePublished":"2023-03-10T17:54:00+00:00","dateModified":"2023-03-10T17:54:03+00:00"},{"@type":"WebSite","@id":"https:\/\/fermentierra.com\/en\/#website","url":"https:\/\/fermentierra.com\/en\/","name":"fermentierra","description":"saveurs lactoferment\u00e9es","inLanguage":"en-US","publisher":{"@id":"https:\/\/fermentierra.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Fermentierra - saveurs lactoferment\u00e9es","og:type":"article","og:title":"Politique en mati\u00e8re de remboursements et de retours - Fermentierra","og:description":"Vue d'ensemble Notre politique de remboursement est de 30 jours. Si 30 jours se sont \u00e9coul\u00e9s depuis votre achat, nous ne pouvons pas vous offrir un remboursement complet. Nous n'acceptons pas les retours de nos produits. Remboursement Vous pouvez pr\u00e9tendre \u00e0 un remboursement si la marchandise a \u00e9t\u00e9 endommag\u00e9e lors de la livraison ou si,","og:url":"https:\/\/fermentierra.com\/en\/remboursements_retours\/","og:image":"https:\/\/qb233zbtdie.preview.infomaniak.website\/wp-content\/uploads\/2025\/04\/cropped-logo-entreprise-fermentierra-detoure.png","og:image:secure_url":"https:\/\/qb233zbtdie.preview.infomaniak.website\/wp-content\/uploads\/2025\/04\/cropped-logo-entreprise-fermentierra-detoure.png","article:published_time":"2023-03-10T17:54:00+00:00","article:modified_time":"2023-03-10T17:54:03+00:00","article:publisher":"https:\/\/www.facebook.com\/fermentierra\/","twitter:card":"summary_large_image","twitter:title":"Politique en mati\u00e8re de remboursements et de retours - Fermentierra","twitter:description":"Vue d'ensemble Notre politique de remboursement est de 30 jours. Si 30 jours se sont \u00e9coul\u00e9s depuis votre achat, nous ne pouvons pas vous offrir un remboursement complet. Nous n'acceptons pas les retours de nos produits. Remboursement Vous pouvez pr\u00e9tendre \u00e0 un remboursement si la marchandise a \u00e9t\u00e9 endommag\u00e9e lors de la livraison ou si,","twitter:image":"https:\/\/qb233zbtdie.preview.infomaniak.website\/wp-content\/uploads\/2025\/04\/cropped-logo-entreprise-fermentierra-detoure.png"},"aioseo_meta_data":{"post_id":"34826","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-03-19 19:48:21","updated":"2025-06-04 06:12:51","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/fermentierra.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPolitique en mati\u00e8re de remboursements et de retours\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/fermentierra.com\/en"},{"label":"Politique en mati\u00e8re de remboursements et de retours","link":"https:\/\/fermentierra.com\/en\/remboursements_retours\/"}],"_links":{"self":[{"href":"https:\/\/fermentierra.com\/en\/wp-json\/wp\/v2\/pages\/34826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fermentierra.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fermentierra.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fermentierra.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fermentierra.com\/en\/wp-json\/wp\/v2\/comments?post=34826"}],"version-history":[{"count":0,"href":"https:\/\/fermentierra.com\/en\/wp-json\/wp\/v2\/pages\/34826\/revisions"}],"wp:attachment":[{"href":"https:\/\/fermentierra.com\/en\/wp-json\/wp\/v2\/media?parent=34826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}