{"id":729,"date":"2020-06-11T08:06:31","date_gmt":"2020-06-11T08:06:31","guid":{"rendered":"https:\/\/fermentierra.com\/?post_type=product&#038;p=729"},"modified":"2026-03-16T15:42:39","modified_gmt":"2026-03-16T15:42:39","slug":"moutarde-noire","status":"publish","type":"product","link":"https:\/\/fermentierra.com\/en\/produit\/moutarde-noire\/","title":{"rendered":"Black Mustard"},"content":{"rendered":"<p>130 g<\/p>","protected":false},"excerpt":{"rendered":"<p>130 g<\/p>","protected":false},"featured_media":39656,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[146],"product_cat":[38,89],"product_tag":[42],"class_list":["post-729","product","type-product","status-publish","has-post-thumbnail","product_brand-fermentierra-mustard","product_cat-condiments","product_cat-condiments-2","product_tag-moutarde","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"130 g\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"vzlGkp0avkDiegdCyCkDigjpo9shigDAmdpk3nXtou4\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/fermentierra.com\/en\/produit\/moutarde-noire\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Fermentierra - saveurs lactoferment\u00e9es\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Moutarde Noire - Fermentierra\" \/>\n\t\t<meta property=\"og:description\" content=\"130 g\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/fermentierra.com\/en\/produit\/moutarde-noire\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/qb233zbtdie.preview.infomaniak.website\/wp-content\/uploads\/2025\/04\/cropped-logo-entreprise-fermentierra-detoure.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/qb233zbtdie.preview.infomaniak.website\/wp-content\/uploads\/2025\/04\/cropped-logo-entreprise-fermentierra-detoure.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-06-11T08:06:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-03-16T15:42:39+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fermentierra\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Moutarde Noire - Fermentierra\" \/>\n\t\t<meta name=\"twitter:description\" content=\"130 g\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/qb233zbtdie.preview.infomaniak.website\/wp-content\/uploads\/2025\/04\/cropped-logo-entreprise-fermentierra-detoure.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/produit\\\/moutarde-noire\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fermentierra.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/brand\\\/fermentierra-mustard\\\/#listItem\",\"name\":\"Fermentierra Mustard\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/brand\\\/fermentierra-mustard\\\/#listItem\",\"position\":2,\"name\":\"Fermentierra Mustard\",\"item\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/brand\\\/fermentierra-mustard\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/produit\\\/moutarde-noire\\\/#listItem\",\"name\":\"Moutarde Noire\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/produit\\\/moutarde-noire\\\/#listItem\",\"position\":3,\"name\":\"Moutarde Noire\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/brand\\\/fermentierra-mustard\\\/#listItem\",\"name\":\"Fermentierra Mustard\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/produit\\\/moutarde-noire\\\/#itempage\",\"url\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/produit\\\/moutarde-noire\\\/\",\"name\":\"Moutarde Noire - Fermentierra\",\"description\":\"130 g\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/produit\\\/moutarde-noire\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/fermentierra.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/IMG_5973-scaled-e1759248493110.jpg\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/produit\\\/moutarde-noire\\\/#mainImage\",\"width\":1630,\"height\":2470},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/produit\\\/moutarde-noire\\\/#mainImage\"},\"datePublished\":\"2020-06-11T08:06:31+00:00\",\"dateModified\":\"2026-03-16T15:42:39+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/#organization\",\"name\":\"Fermentierra\",\"description\":\"Fermentierra saveurs lactoferment\\u00e9es\",\"url\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/qb233zbtdie.preview.infomaniak.website\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/cropped-logo-entreprise-fermentierra-detoure.png\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/produit\\\/moutarde-noire\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/produit\\\/moutarde-noire\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fermentierra\\\/\",\"https:\\\/\\\/www.instagram.com\\\/fermentierra\\\/\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/\",\"name\":\"fermentierra\",\"description\":\"saveurs lactoferment\\u00e9es\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/fermentierra.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Black mustard - Fermentierra","description":"130 g","canonical_url":"https:\/\/fermentierra.com\/en\/produit\/moutarde-noire\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"vzlGkp0avkDiegdCyCkDigjpo9shigDAmdpk3nXtou4","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/fermentierra.com\/en\/produit\/moutarde-noire\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/fermentierra.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/fermentierra.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/fermentierra.com\/en\/brand\/fermentierra-mustard\/#listItem","name":"Fermentierra Mustard"}},{"@type":"ListItem","@id":"https:\/\/fermentierra.com\/en\/brand\/fermentierra-mustard\/#listItem","position":2,"name":"Fermentierra Mustard","item":"https:\/\/fermentierra.com\/en\/brand\/fermentierra-mustard\/","nextItem":{"@type":"ListItem","@id":"https:\/\/fermentierra.com\/en\/produit\/moutarde-noire\/#listItem","name":"Moutarde Noire"},"previousItem":{"@type":"ListItem","@id":"https:\/\/fermentierra.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/fermentierra.com\/en\/produit\/moutarde-noire\/#listItem","position":3,"name":"Moutarde Noire","previousItem":{"@type":"ListItem","@id":"https:\/\/fermentierra.com\/en\/brand\/fermentierra-mustard\/#listItem","name":"Fermentierra Mustard"}}]},{"@type":"ItemPage","@id":"https:\/\/fermentierra.com\/en\/produit\/moutarde-noire\/#itempage","url":"https:\/\/fermentierra.com\/en\/produit\/moutarde-noire\/","name":"Moutarde Noire - Fermentierra","description":"130 g","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/fermentierra.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/fermentierra.com\/en\/produit\/moutarde-noire\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/fermentierra.com\/wp-content\/uploads\/2020\/06\/IMG_5973-scaled-e1759248493110.jpg","@id":"https:\/\/fermentierra.com\/en\/produit\/moutarde-noire\/#mainImage","width":1630,"height":2470},"primaryImageOfPage":{"@id":"https:\/\/fermentierra.com\/en\/produit\/moutarde-noire\/#mainImage"},"datePublished":"2020-06-11T08:06:31+00:00","dateModified":"2026-03-16T15:42:39+00:00"},{"@type":"Organization","@id":"https:\/\/fermentierra.com\/en\/#organization","name":"Fermentierra","description":"Fermentierra saveurs lactoferment\u00e9es","url":"https:\/\/fermentierra.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/qb233zbtdie.preview.infomaniak.website\/wp-content\/uploads\/2025\/04\/cropped-logo-entreprise-fermentierra-detoure.png","@id":"https:\/\/fermentierra.com\/en\/produit\/moutarde-noire\/#organizationLogo"},"image":{"@id":"https:\/\/fermentierra.com\/en\/produit\/moutarde-noire\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/fermentierra\/","https:\/\/www.instagram.com\/fermentierra\/"]},{"@type":"WebSite","@id":"https:\/\/fermentierra.com\/en\/#website","url":"https:\/\/fermentierra.com\/en\/","name":"fermentierra","description":"saveurs lactoferment\u00e9es","inLanguage":"en-US","publisher":{"@id":"https:\/\/fermentierra.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Fermentierra - saveurs lactoferment\u00e9es","og:type":"article","og:title":"Moutarde Noire - Fermentierra","og:description":"130 g","og:url":"https:\/\/fermentierra.com\/en\/produit\/moutarde-noire\/","og:image":"https:\/\/qb233zbtdie.preview.infomaniak.website\/wp-content\/uploads\/2025\/04\/cropped-logo-entreprise-fermentierra-detoure.png","og:image:secure_url":"https:\/\/qb233zbtdie.preview.infomaniak.website\/wp-content\/uploads\/2025\/04\/cropped-logo-entreprise-fermentierra-detoure.png","article:published_time":"2020-06-11T08:06:31+00:00","article:modified_time":"2026-03-16T15:42:39+00:00","article:publisher":"https:\/\/www.facebook.com\/fermentierra\/","twitter:card":"summary_large_image","twitter:title":"Moutarde Noire - Fermentierra","twitter:description":"130 g","twitter:image":"https:\/\/qb233zbtdie.preview.infomaniak.website\/wp-content\/uploads\/2025\/04\/cropped-logo-entreprise-fermentierra-detoure.png"},"aioseo_meta_data":{"post_id":"729","title":"#post_title #separator_sa #site_title","description":"#post_excerpt","keywords":null,"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2023-03-19 19:50:14","updated":"2026-08-11 09:59:17","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/fermentierra.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/fermentierra.com\/en\/brand\/fermentierra-mustard\/\" title=\"Fermentierra Mustard\">Fermentierra Mustard<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMoutarde Noire\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/fermentierra.com\/en"},{"label":"Fermentierra Mustard","link":"https:\/\/fermentierra.com\/en\/brand\/fermentierra-mustard\/"},{"label":"Moutarde Noire","link":"https:\/\/fermentierra.com\/en\/produit\/moutarde-noire\/"}],"_links":{"self":[{"href":"https:\/\/fermentierra.com\/en\/wp-json\/wp\/v2\/product\/729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fermentierra.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fermentierra.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/fermentierra.com\/en\/wp-json\/wp\/v2\/comments?post=729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fermentierra.com\/en\/wp-json\/wp\/v2\/media\/39656"}],"wp:attachment":[{"href":"https:\/\/fermentierra.com\/en\/wp-json\/wp\/v2\/media?parent=729"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fermentierra.com\/en\/wp-json\/wp\/v2\/product_brand?post=729"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fermentierra.com\/en\/wp-json\/wp\/v2\/product_cat?post=729"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fermentierra.com\/en\/wp-json\/wp\/v2\/product_tag?post=729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}